

{"id":214,"date":"2018-08-13T12:25:59","date_gmt":"2018-08-13T15:25:59","guid":{"rendered":"http:\/\/gnugraf.org\/2018\/?p=214"},"modified":"2018-07-16T12:26:13","modified_gmt":"2018-07-16T15:26:13","slug":"palestrante-confirmado-sami-souza","status":"publish","type":"post","link":"http:\/\/gnugraf.org\/2018\/palestrante-confirmado-sami-souza\/","title":{"rendered":"Palestrante confirmado &#8211; Sami Souza"},"content":{"rendered":"<h2><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"215\" data-permalink=\"http:\/\/gnugraf.org\/2018\/palestrante-confirmado-sami-souza\/sami\/\" data-orig-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/sami.png?fit=724%2C724\" data-orig-size=\"724,724\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"sami\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/sami.png?fit=590%2C590\" class=\"alignnone  wp-image-215\" src=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/sami.png?resize=140%2C140\" alt=\"sami\" width=\"140\" height=\"140\" srcset=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/sami.png?w=724 724w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/sami.png?resize=150%2C150 150w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/sami.png?resize=300%2C300 300w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/sami.png?resize=600%2C600 600w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/sami.png?resize=100%2C100 100w\" sizes=\"auto, (max-width: 140px) 100vw, 140px\" \/> Sami Souza<\/h2>\n<p>Designer, ilustrador e quadrinista que desenvolve todo o seu trabalho criativo fazendo uso de ferramentas opensource. Seu contato com o meio acad\u00eamico por mais de uma d\u00e9cada ilustrando livros did\u00e1ticos lapidou o gosto por palestrar sobre o of\u00edcio das artes gr\u00e1ficas, do mercado de criatividade e da liberdade de conhecimento.<\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"590\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;http:\\\/\\\/gnugraf.org\\\/2018\\\/palestrante-confirmado-sami-souza\\\/&quot;,&quot;likes_blog_id&quot;:139697713}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 590px; height: 287px;\" data-original-width=\"590\" data-original-height=\"287\" > <div class=\"gallery-group images-1\" style=\"width: 381px; height: 287px;\" data-original-width=\"381\" data-original-height=\"287\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"http:\/\/gnugraf.org\/2018\/palestrante-confirmado-sami-souza\/36399266_1862084017145098_5201520869393825792_n\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"377\"> <meta itemprop=\"height\" content=\"283\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"217\" data-orig-file=\"http:\/\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/36399266_1862084017145098_5201520869393825792_n.jpg\" data-orig-size=\"960,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"36399266_1862084017145098_5201520869393825792_n\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/36399266_1862084017145098_5201520869393825792_n.jpg?fit=300%2C225\" data-large-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/36399266_1862084017145098_5201520869393825792_n.jpg?fit=590%2C443\" src=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/36399266_1862084017145098_5201520869393825792_n.jpg?w=377&#038;h=283\" srcset=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/36399266_1862084017145098_5201520869393825792_n.jpg?w=960 960w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/36399266_1862084017145098_5201520869393825792_n.jpg?resize=300%2C225 300w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/36399266_1862084017145098_5201520869393825792_n.jpg?resize=768%2C576 768w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/36399266_1862084017145098_5201520869393825792_n.jpg?resize=600%2C450 600w\" width=\"377\" height=\"283\" loading=\"lazy\" data-original-width=\"377\" data-original-height=\"283\" itemprop=\"http:\/\/schema.org\/image\" title=\"36399266_1862084017145098_5201520869393825792_n\" alt=\"36399266_1862084017145098_5201520869393825792_n\" style=\"width: 377px; height: 283px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 209px; height: 287px;\" data-original-width=\"209\" data-original-height=\"287\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"http:\/\/gnugraf.org\/2018\/palestrante-confirmado-sami-souza\/27540707_1701182989901869_6418827440127884864_n\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"205\"> <meta itemprop=\"height\" content=\"283\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"218\" data-orig-file=\"http:\/\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/27540707_1701182989901869_6418827440127884864_n.jpg\" data-orig-size=\"697,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"27540707_1701182989901869_6418827440127884864_n\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/27540707_1701182989901869_6418827440127884864_n.jpg?fit=218%2C300\" data-large-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/27540707_1701182989901869_6418827440127884864_n.jpg?fit=590%2C813\" src=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/27540707_1701182989901869_6418827440127884864_n.jpg?w=205&#038;h=283\" srcset=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/27540707_1701182989901869_6418827440127884864_n.jpg?w=697 697w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/27540707_1701182989901869_6418827440127884864_n.jpg?resize=218%2C300 218w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/27540707_1701182989901869_6418827440127884864_n.jpg?resize=600%2C826 600w\" width=\"205\" height=\"283\" loading=\"lazy\" data-original-width=\"205\" data-original-height=\"283\" itemprop=\"http:\/\/schema.org\/image\" title=\"27540707_1701182989901869_6418827440127884864_n\" alt=\"27540707_1701182989901869_6418827440127884864_n\" style=\"width: 205px; height: 283px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 590px; height: 273px;\" data-original-width=\"590\" data-original-height=\"273\" > <div class=\"gallery-group images-1\" style=\"width: 350px; height: 273px;\" data-original-width=\"350\" data-original-height=\"273\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"http:\/\/gnugraf.org\/2018\/palestrante-confirmado-sami-souza\/photo_2018-07-16_12-20-31\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"346\"> <meta itemprop=\"height\" content=\"269\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"219\" data-orig-file=\"http:\/\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-20-31.jpg\" data-orig-size=\"767,597\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"photo_2018-07-16_12-20-31\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-20-31.jpg?fit=300%2C234\" data-large-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-20-31.jpg?fit=590%2C459\" src=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-20-31.jpg?w=346&#038;h=269\" srcset=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-20-31.jpg?w=767 767w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-20-31.jpg?resize=300%2C234 300w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-20-31.jpg?resize=600%2C467 600w\" width=\"346\" height=\"269\" loading=\"lazy\" data-original-width=\"346\" data-original-height=\"269\" itemprop=\"http:\/\/schema.org\/image\" title=\"photo_2018-07-16_12-20-31\" alt=\"photo_2018-07-16_12-20-31\" style=\"width: 346px; height: 269px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 240px; height: 273px;\" data-original-width=\"240\" data-original-height=\"273\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"http:\/\/gnugraf.org\/2018\/palestrante-confirmado-sami-souza\/photo_2018-04-04_08-50-23\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"236\"> <meta itemprop=\"height\" content=\"269\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"220\" data-orig-file=\"http:\/\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-04-04_08-50-23.jpg\" data-orig-size=\"675,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"photo_2018-04-04_08-50-23\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-04-04_08-50-23.jpg?fit=264%2C300\" data-large-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-04-04_08-50-23.jpg?fit=590%2C671\" src=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-04-04_08-50-23.jpg?w=236&#038;h=269\" srcset=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-04-04_08-50-23.jpg?w=675 675w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-04-04_08-50-23.jpg?resize=264%2C300 264w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-04-04_08-50-23.jpg?resize=600%2C683 600w\" width=\"236\" height=\"269\" loading=\"lazy\" data-original-width=\"236\" data-original-height=\"269\" itemprop=\"http:\/\/schema.org\/image\" title=\"photo_2018-04-04_08-50-23\" alt=\"photo_2018-04-04_08-50-23\" style=\"width: 236px; height: 269px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 590px; height: 273px;\" data-original-width=\"590\" data-original-height=\"273\" > <div class=\"gallery-group images-1\" style=\"width: 198px; height: 273px;\" data-original-width=\"198\" data-original-height=\"273\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"http:\/\/gnugraf.org\/2018\/palestrante-confirmado-sami-souza\/photo_2018-07-16_12-19-10\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"194\"> <meta itemprop=\"height\" content=\"269\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"221\" data-orig-file=\"http:\/\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-10.jpg\" data-orig-size=\"925,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"photo_2018-07-16_12-19-10\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-10.jpg?fit=217%2C300\" data-large-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-10.jpg?fit=590%2C816\" src=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-10.jpg?w=194&#038;h=269\" srcset=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-10.jpg?w=925 925w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-10.jpg?resize=217%2C300 217w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-10.jpg?resize=768%2C1063 768w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-10.jpg?resize=740%2C1024 740w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-10.jpg?resize=600%2C830 600w\" width=\"194\" height=\"269\" loading=\"lazy\" data-original-width=\"194\" data-original-height=\"269\" itemprop=\"http:\/\/schema.org\/image\" title=\"photo_2018-07-16_12-19-10\" alt=\"photo_2018-07-16_12-19-10\" style=\"width: 194px; height: 269px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 198px; height: 273px;\" data-original-width=\"198\" data-original-height=\"273\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"http:\/\/gnugraf.org\/2018\/palestrante-confirmado-sami-souza\/photo_2018-07-16_12-19-00\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"194\"> <meta itemprop=\"height\" content=\"269\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"222\" data-orig-file=\"http:\/\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-00.jpg\" data-orig-size=\"924,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"photo_2018-07-16_12-19-00\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-00.jpg?fit=217%2C300\" data-large-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-00.jpg?fit=590%2C818\" src=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-00.jpg?w=194&#038;h=269\" srcset=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-00.jpg?w=924 924w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-00.jpg?resize=217%2C300 217w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-00.jpg?resize=768%2C1064 768w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-00.jpg?resize=739%2C1024 739w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-19-00.jpg?resize=600%2C831 600w\" width=\"194\" height=\"269\" loading=\"lazy\" data-original-width=\"194\" data-original-height=\"269\" itemprop=\"http:\/\/schema.org\/image\" title=\"photo_2018-07-16_12-19-00\" alt=\"photo_2018-07-16_12-19-00\" style=\"width: 194px; height: 269px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 194px; height: 273px;\" data-original-width=\"194\" data-original-height=\"273\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"http:\/\/gnugraf.org\/2018\/palestrante-confirmado-sami-souza\/photo_2018-07-16_12-18-18\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"190\"> <meta itemprop=\"height\" content=\"269\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"223\" data-orig-file=\"http:\/\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-18-18.jpg\" data-orig-size=\"509,720\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"photo_2018-07-16_12-18-18\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-18-18.jpg?fit=212%2C300\" data-large-file=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-18-18.jpg?fit=509%2C720\" src=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-18-18.jpg?w=190&#038;h=269\" srcset=\"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-18-18.jpg?w=509 509w, https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/photo_2018-07-16_12-18-18.jpg?resize=212%2C300 212w\" width=\"190\" height=\"269\" loading=\"lazy\" data-original-width=\"190\" data-original-height=\"269\" itemprop=\"http:\/\/schema.org\/image\" title=\"photo_2018-07-16_12-18-18\" alt=\"photo_2018-07-16_12-18-18\" style=\"width: 190px; height: 269px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<p>O evento acontecer\u00e1 nos dias <b>14 e 15 de <\/b><strong>Setembro<\/strong> dentro do pr\u00f3prio campus da <b>ESD<\/b>I, <b>Rua do Passeio, 80 \u2013 Centro<\/b><b> \u2013 Rio de Janeiro<\/b><\/p>\n<p>Em frente ao <b>Passeio P\u00fablico<\/b> e ao lado da <b>escola de m\u00fasica da UFRJ<\/b>.<\/p>\n<link rel='stylesheet' id='osm-ol3-css-css' href='http:\/\/gnugraf.org\/2018\/wp-content\/plugins\/osm\/js\/OL\/10.9.0\/ol.css?ver=10.9.0&#038;ver=7.0.4' media='all' \/>\n<link rel='stylesheet' id='osm-ol3-ext-css-css' href='http:\/\/gnugraf.org\/2018\/wp-content\/plugins\/osm\/css\/osm_map_v3.css?ver=1.0.0&#038;ver=7.0.4' media='all' \/>\n<link rel='stylesheet' id='osm-map-css-css' href='http:\/\/gnugraf.org\/2018\/wp-content\/plugins\/osm\/css\/osm_map.css?ver=1.0.0&#038;ver=7.0.4' media='all' \/>\n<script id=\"wp-polyfill-js\" src=\"http:\/\/gnugraf.org\/2018\/wp-includes\/js\/dist\/vendor\/wp-polyfill.min.js?ver=3.15.0\"><\/script>\n<script id=\"osm-ol3-library-js\" src=\"http:\/\/gnugraf.org\/2018\/wp-content\/plugins\/osm\/js\/OL\/10.9.0\/ol.js?ver=10.9.0\"><\/script>\n<script id=\"osm-ol3-ext-library-js\" src=\"http:\/\/gnugraf.org\/2018\/wp-content\/plugins\/osm\/js\/osm-v3-plugin-lib.js?ver=1.0.0\"><\/script>\n<script id=\"osm-ol3-metabox-events-js\" src=\"http:\/\/gnugraf.org\/2018\/wp-content\/plugins\/osm\/js\/osm-metabox-events.js?ver=1.0.0\"><\/script>\n<script id=\"jquery-core-js\" src=\"http:\/\/gnugraf.org\/2018\/wp-includes\/js\/jquery\/jquery.min.js?ver=3.7.1\"><\/script>\n<script id=\"jquery-migrate-js\" src=\"http:\/\/gnugraf.org\/2018\/wp-includes\/js\/jquery\/jquery-migrate.min.js?ver=3.4.1\"><\/script>\n<script id=\"osm-map-startup-js-extra\">\nvar translations = {\"openlayer\":\"open layer\",\"openlayerAtStartup\":\"open layer at startup\",\"generateLink\":\"link to this map with opened layers\",\"shortDescription\":\"short description\",\"generatedShortCode\":\"to get a text control link paste this code in your wordpress editor\",\"closeLayer\":\"close layer\",\"cantGenerateLink\":\"put this string in the existing map short code to control this map\"};\n\/\/# sourceURL=osm-map-startup-js-extra\n<\/script>\n<script id=\"osm-map-startup-js\" src=\"http:\/\/gnugraf.org\/2018\/wp-content\/plugins\/osm\/js\/osm-startup-lib.js?ver=V6.2.6\"><\/script>\n\n        <div id=\"map_ol3js_1\"\n       class=\"osm-map-container undefined\"\n             data-map_name=\"undefined\"\n             data-map=\"map_ol3js_1\"\n             data-autoshow=\"no\"\n             style=\"width:100%;\n                    max-width:100%;\n                    height:450px;\n                    display:block;\n                    overflow:hidden;\n                    border:2px solid grey;\n                    position: relative;\">\n          <div id=\"map_ol3js_1_popup\" class=\"ol-popup\">\n            <a href=\"#\" id=\"map_ol3js_1_popup-closer\" class=\"ol-popup-closer\"><\/a>\n            <div id=\"map_ol3js_1_popup-content\"><\/div>\n          <\/div>\n        <\/div>\n    <script type=\"text\/javascript\">\n\t\t\t  vectorM['map_ol3js_1'] = [];\n\t        \n        var raster = getTileLayer(\"osm\",\"NoKey\");\t\t\t\n\n\t\t\t  var map_ol3js_1 = new ol.Map({\n\t\t\t\tinteractions: ol.interaction.defaults.defaults({mouseWheelZoom:false}),\n\t\t\t\tlayers: [raster],\n\t\t\t\ttarget: \"map_ol3js_1\",\n\t\t\t\tview: new ol.View({\n\t\t\t\t  center: ol.proj.transform([-43.1782,-22.9130], \"EPSG:4326\", \"EPSG:3857\"),\n\t\t\t\t  zoom: 19\n\t\t\t\t})\n\t\t\t  });\n\t\t\t  addControls2Map(map_ol3js_1,1,0,3,1,5,6,7,1,1);\nosm_addPopupClickhandler(map_ol3js_1,  \"map_ol3js_1\"); \nosm_addMouseHover(map_ol3js_1); <\/script>\n","protected":false},"excerpt":{"rendered":"<p>Sami Souza Designer, ilustrador e quadrinista que desenvolve todo o seu trabalho criativo fazendo uso de ferramentas opensource. Seu contato com o meio acad\u00eamico por mais de uma d\u00e9cada ilustrando livros did\u00e1ticos lapidou o gosto por palestrar sobre o of\u00edcio das artes gr\u00e1ficas, do mercado de criatividade e da liberdade de conhecimento. O evento acontecer\u00e1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":216,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[16],"tags":[],"class_list":["post-214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9s9KV-3s","jetpack_likes_enabled":true,"jetpack-related-posts":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/gnugraf.org\/2018\/wp-content\/uploads\/2018\/07\/27654674_1708509939169174_139054979019805106_n.jpg?fit=766%2C759","_links":{"self":[{"href":"http:\/\/gnugraf.org\/2018\/wp-json\/wp\/v2\/posts\/214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/gnugraf.org\/2018\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/gnugraf.org\/2018\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/gnugraf.org\/2018\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/gnugraf.org\/2018\/wp-json\/wp\/v2\/comments?post=214"}],"version-history":[{"count":1,"href":"http:\/\/gnugraf.org\/2018\/wp-json\/wp\/v2\/posts\/214\/revisions"}],"predecessor-version":[{"id":224,"href":"http:\/\/gnugraf.org\/2018\/wp-json\/wp\/v2\/posts\/214\/revisions\/224"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/gnugraf.org\/2018\/wp-json\/wp\/v2\/media\/216"}],"wp:attachment":[{"href":"http:\/\/gnugraf.org\/2018\/wp-json\/wp\/v2\/media?parent=214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/gnugraf.org\/2018\/wp-json\/wp\/v2\/categories?post=214"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/gnugraf.org\/2018\/wp-json\/wp\/v2\/tags?post=214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}